{"id":3797,"date":"2025-02-21T11:03:25","date_gmt":"2025-02-21T11:03:25","guid":{"rendered":"https:\/\/www.colomio.com\/desenhos-para-colorir\/veiculos\/escavadeira"},"modified":"2026-04-21 15:01:08","modified_gmt":"2026-04-21T15:01:08","slug":"escavadeira","status":"publish","type":"page","link":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira","title":{"rendered":"P\u00e1gina para colorir com escavadeira: imprima gr\u00e1tis, escolha as cores e m\u00e3os \u00e0 obra!"},"content":{"rendered":"<p>As p\u00e1ginas para colorir de escavadoras s\u00e3o desenhos simples e divertidos que permitem \u00e0s crian\u00e7as pintar cenas com m\u00e1quinas de constru\u00e7\u00e3o, desde a escavadora cl\u00e1ssica at\u00e9 modelos mais modernos. Uma p\u00e1gina para colorir de escavadora oferece contornos claros e \u00e1reas amplas para crian\u00e7as mais novas, enquanto conjuntos de p\u00e1ginas para colorir podem incluir detalhes adicionais para crian\u00e7as mais velhas que gostam de desafios. Estas p\u00e1ginas para colorir s\u00e3o \u00f3timas tanto para beb\u00e9s e crian\u00e7as em idade pr\u00e9-escolar como para crian\u00e7as mais velhas: os mais pequenos beneficiam de formas grandes e linhas grossas, enquanto os mais crescidos podem praticar sombreamento e detalhes t\u00e9cnicos. Pode us\u00e1-las em casa durante a hora tranquila, em sala de aula como atividade tem\u00e1tica, no ensino dom\u00e9stico para apoiar unidades sobre m\u00e1quinas e constru\u00e7\u00e3o, ou em viagens para manter as m\u00e3os e mentes ocupadas. Para pais e educadores, as p\u00e1ginas para colorir de escavadoras s\u00e3o uma ferramenta acess\u00edvel que promove criatividade, reconhecimento de cores, coordena\u00e7\u00e3o olho-m\u00e3o e motricidade fina, al\u00e9m de ajudar na concentra\u00e7\u00e3o e na paci\u00eancia. Tamb\u00e9m s\u00e3o um ponto de partida para conversas sobre engenharia simples, seguran\u00e7a no trabalho e diferentes tipos de ve\u00edculos, tornando a tarefa de colorir tanto divertida quanto educativa.<\/p><div class=\"paintings\">\n  <div class=\"grid grid-cols-1 sm:grid-cols-2 md:grid-cols-2 lg:grid-cols-4 gap-6\"><!-- colorstream-->\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page-bucket-tracks.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\" alt=\"Uma p\u00e1gina para colorir de uma escavadora em estilo cartoon, mostrando uma m\u00e1quina de escava\u00e7\u00e3o com lagartas, balde grande, bra\u00e7o e pedras simples no ch\u00e3o.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina para colorir de escavadora com balde e lagartas\" loading=\"eager\" fetchpriority=\"high\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page-bucket-tracks.png\" style=\"text-decoration-line: none;\">Escavadora com balde e lagartas<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page-bucket-tracks.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1778561346549\" data-ugc-likes=\"0\" data-ugc-title=\"MY EKSCAVATOR\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-05-12\/thumb_1778561346549.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1778561346549\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora com balde e lagartas 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-05-12\/thumb_1778561346549.jpg\" alt=\"Vers\u00e3o colorida: Escavadora com balde e lagartas\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1778561346549\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\/escavadora-obra-com-operario\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.png\" alt=\"Uma escavadora com uma grande p\u00e1 est\u00e1 em um canteiro de obras ao lado de um trabalhador com capacete e colete de seguran\u00e7a.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina para colorir de escavadora em um canteiro de obras\" loading=\"eager\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\/escavadora-obra-com-operario\" style=\"text-decoration-line: none;\">Escavadora em um canteiro de obras<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page-construction-site-with-worker.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-construction-site-with-worker.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1775496331252\" data-ugc-likes=\"2\" data-ugc-title=\"Go\u015b\u0107 #1252\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-04-06\/thumb_1775496331252.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1775496331252\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-04-06\/thumb_1775496331252.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1775496331252\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1775732619908\" data-ugc-likes=\"1\" data-ugc-title=\"Nisses R\u00f6da Fara\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-04-09\/thumb_1775732619908.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1775732619908\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-04-09\/thumb_1775732619908.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1775732619908\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1777660971955\" data-ugc-likes=\"0\" data-ugc-title=\"Guest #1955\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-05-01\/thumb_1777660971955.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1777660971955\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-05-01\/thumb_1777660971955.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1777660971955\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fnew%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page-construction-site-with-worker.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-in-a-sunny-landscape.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.png\" alt=\"Uma p\u00e1gina de colorir detalhada com uma escavadora em uma paisagem c\u00eanica com \u00e1rvores e sol.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina de Colorir Escavadora para Crian\u00e7as Imprim\u00edvel\" loading=\"eager\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-in-a-sunny-landscape.png\" style=\"text-decoration-line: none;\">Escavadora em uma paisagem ensolarada<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-in-a-sunny-landscape.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-in-a-sunny-landscape.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1770912999460\" data-ugc-likes=\"1\" data-ugc-title=\"Felix\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-12\/thumb_1770912999460.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1770912999460\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-12\/thumb_1770912999460.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1770912999460\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1770207384788\" data-ugc-likes=\"1\" data-ugc-title=\"Bagger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-04\/thumb_1770207384788.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1770207384788\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-04\/thumb_1770207384788.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1770207384788\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1772899554026\" data-ugc-likes=\"0\" data-ugc-title=\"Milans Minibagger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-07\/thumb_1772899554026.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1772899554026\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-07\/thumb_1772899554026.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em uma paisagem ensolarada\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1772899554026\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fnew%2Fvehicles%2Fexcavator%2Fexcavator-in-a-sunny-landscape.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fconstruction-site-crane-truck-3f0ed3.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.png\" alt=\"Uma p\u00e1gina para colorir apresentando um canteiro de obras com um guindaste levantando um balde sobre um caminh\u00e3o cheio de pedras.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina para colorir de canteiro de obras com guindaste e caminh\u00e3o\" loading=\"eager\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fconstruction-site-crane-truck-3f0ed3.png\" style=\"text-decoration-line: none;\">Cena de canteiro de obras<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fconstruction-site-crane-truck-3f0ed3.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/construction-site-crane-truck-3f0ed3.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1771760761719\" data-ugc-likes=\"3\" data-ugc-title=\"KULES AUTO\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-22\/thumb_1771760761719.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1771760761719\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Cena de canteiro de obras 3 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-22\/thumb_1771760761719.jpg\" alt=\"Vers\u00e3o colorida: Cena de canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1771760761719\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">3 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1768049445251\" data-ugc-likes=\"3\" data-ugc-title=\"MATS\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-10\/thumb_1768049445251.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1768049445251\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Cena de canteiro de obras 3 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-10\/thumb_1768049445251.jpg\" alt=\"Vers\u00e3o colorida: Cena de canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1768049445251\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">3 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1767719109958\" data-ugc-likes=\"2\" data-ugc-title=\"bagga 78 ps\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-06\/thumb_1767719109958.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1767719109958\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Cena de canteiro de obras 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-06\/thumb_1767719109958.jpg\" alt=\"Vers\u00e3o colorida: Cena de canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1767719109958\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<section class=\"shortcode-fullrow content-block\" data-insert=\"after-4\">\n  <div class=\"content-block__inner\">\n<link rel=\"stylesheet\" href=\"https:\/\/media.colomio.com\/mix\/cp-generator.css\">\n\n<div class=\"hc-generator-wrapper\">\n  <form action=\"https:\/\/www.colomio.com\/pt-pt\/gerador-paginas-para-colorir-ia\" method=\"get\" class=\"hc-generator-form\">\n    <div class=\"hc-generator-title\"><b><big>\u2b50 Crie a sua pr\u00f3pria p\u00e1gina para colorir \ud83e\udd84<\/big><\/b><\/div>\n    <div class=\"hc-generator-text\">D\u00ea vida \u00e0s suas ideias gratuitamente!<\/div>\n    <label for=\"hc-prompt-inline\">O que devo desenhar para voc\u00ea?<\/label>\n    <div class=\"hc-generator-row\">\n      <div class=\"hc-input-wrap\" id=\"hc-input-wrap\">\n        <input id=\"hc-prompt-inline\" name=\"prompt\" type=\"text\" class=\"hc-generator-input\" placeholder=\"Exemplo: gatinho fofo e cachorrinho\" autocomplete=\"off\">\n        <span class=\"hc-caret\" aria-hidden=\"true\"><\/span>\n      <\/div>\n      <button type=\"submit\" class=\"hc-generator-button\">Criar p\u00e1gina para colorir<\/button>\n    <\/div>\n    <div class=\"hc-upload-section\">\n      <div class=\"hc-or-divider\">OU<\/div>\n      <div class=\"hc-upload-text\">use a sua pr\u00f3pria imagem para gerar uma p\u00e1gina para colorir gratuitamente.<\/div>\n      <div class=\"hc-upload-preview-row\">\n        <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/mix\/image-to-coloring.gif\" alt=\"Foto para p\u00e1gina de colorir\" class=\"hc-upload-gif\" loading=\"lazy\">\n        <a href=\"https:\/\/www.colomio.com\/pt-pt\/gerador-paginas-para-colorir-ia?upload=1\" class=\"hc-upload-button\">\n          <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" style=\"vertical-align:-3px;margin-right:8px\"><path d=\"M21 15v4a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2v-4\"><\/path><polyline points=\"17 8 12 3 7 8\"><\/polyline><line x1=\"12\" y1=\"3\" x2=\"12\" y2=\"15\"><\/line><\/svg>Enviar foto\n        <\/a>\n      <\/div>\n    <\/div>\n  <\/form>\n<\/div>\n\n<script>\n(function(){const input=document.getElementById(\"hc-prompt-inline\");const wrap=document.getElementById(\"hc-input-wrap\");if(!input||!wrap)return;wrap.classList.add(\"hc-caret-on\");const syncValueState=()=>{input.value&&input.value.length>0?wrap.classList.add(\"hc-has-value\"):wrap.classList.remove(\"hc-has-value\")};syncValueState();input.addEventListener(\"input\",syncValueState);input.addEventListener(\"focus\",()=>{wrap.classList.remove(\"hc-caret-on\")});input.addEventListener(\"blur\",()=>{if(!input.value)wrap.classList.add(\"hc-caret-on\")});wrap.addEventListener(\"mousedown\",e=>{if(e.target!==input)e.preventDefault();input.focus({preventScroll:true})})})();\n<\/script>\n  <\/div>\n<\/section>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-at-construction-site.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/excavator-at-construction-site.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/excavator-at-construction-site.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/excavator-at-construction-site.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/excavator-at-construction-site.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-at-construction-site.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/excavator-at-construction-site.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-at-construction-site.png\" alt=\"Uma ilustra\u00e7\u00e3o detalhada em preto e branco de uma escavadora em um canteiro de obras, cercada por pedras e carros.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina para Colorir Escavadora para Crian\u00e7as para Imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-at-construction-site.png\" style=\"text-decoration-line: none;\">Escavadora em um canteiro de obras<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-at-construction-site.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-at-construction-site.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763303620220\" data-ugc-likes=\"3\" data-ugc-title=\"Basel Bagger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-11-16\/thumb_1763303620220.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763303620220\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 3 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-11-16\/thumb_1763303620220.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763303620220\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">3 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1772809681946\" data-ugc-likes=\"0\" data-ugc-title=\"bbgfghjhbb vvuurrwwxx\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-06\/thumb_1772809681946.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1772809681946\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-06\/thumb_1772809681946.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1772809681946\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1770131001840\" data-ugc-likes=\"0\" data-ugc-title=\"Guest #1840\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-02-03\/thumb_1770131001840.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1770131001840\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-02-03\/thumb_1770131001840.jpg\" alt=\"Vers\u00e3o colorida: Escavadora em um canteiro de obras\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1770131001840\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fnew%2Fvehicles%2Fexcavator%2Fexcavator-at-construction-site.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\/escavadora-lagartas-braco-articulado\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/excavator-coloring-page.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/excavator-coloring-page.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page.png\" alt=\"Um contorno detalhado de uma escavadora em um canteiro de obras com nuvens e sol.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina para Colorir Escavadora para Crian\u00e7as\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\/escavadora-lagartas-braco-articulado\" style=\"text-decoration-line: none;\">Divers\u00e3o de colorir com a escavadora<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1776441650539\" data-ugc-likes=\"2\" data-ugc-title=\"asfghk\u00f6\u00e4\u00f6ujghzrfvbz\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-04-17\/thumb_1776441650539.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1776441650539\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-04-17\/thumb_1776441650539.jpg\" alt=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1776441650539\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1761134723373\" data-ugc-likes=\"2\" data-ugc-title=\"Bagger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-22\/thumb_1761134723373.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1761134723373\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-22\/thumb_1761134723373.jpg\" alt=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1761134723373\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1771421415127\" data-ugc-likes=\"1\" data-ugc-title=\"Bagger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-18\/thumb_1771421415127.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1771421415127\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-18\/thumb_1771421415127.jpg\" alt=\"Vers\u00e3o colorida: Divers\u00e3o de colorir com a escavadora\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1771421415127\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fnew%2Fvehicles%2Fexcavator%2Fexcavator-coloring-page.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fcute-cartoon-excavator-coloring.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.png\" alt=\"Uma escavadora cartoon alegre com um rosto sorridente, pronta para colorir. Apresenta um design detalhado com esteiras e um grande bra\u00e7o de escava\u00e7\u00e3o.\" class=\"w-full h-64 md:h-48 object-contain\" title=\"P\u00e1gina de Colorir de Escavadora Cartoon Fofa para Crian\u00e7as\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fcute-cartoon-excavator-coloring.png\" style=\"text-decoration-line: none;\">P\u00e1gina de colorir de escavadora alegre<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=new%2Fvehicles%2Fexcavator%2Fcute-cartoon-excavator-coloring.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/cute-cartoon-excavator-coloring.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763061244954\" data-ugc-likes=\"1\" data-ugc-title=\"excavator\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-13\/thumb_1763061244954.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763061244954\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: P\u00e1gina de colorir de escavadora alegre 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-13\/thumb_1763061244954.jpg\" alt=\"Vers\u00e3o colorida: P\u00e1gina de colorir de escavadora alegre\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763061244954\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763278038205\" data-ugc-likes=\"0\" data-ugc-title=\"Elis\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-16\/thumb_1763278038205.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763278038205\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: P\u00e1gina de colorir de escavadora alegre 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-16\/thumb_1763278038205.jpg\" alt=\"Vers\u00e3o colorida: P\u00e1gina de colorir de escavadora alegre\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763278038205\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fexcavator.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/excavator.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/excavator.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/excavator.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/excavator.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/excavator.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/excavator.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/excavator.png\" alt=\"Imagem de escavadeira para colorir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Escavadeira para colorir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fexcavator.png\" style=\"text-decoration-line: none;\">Escavadeira para colorir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fexcavator.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/excavator.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1769086644606\" data-ugc-likes=\"2\" data-ugc-title=\"zaki 2\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-01-22\/thumb_1769086644606.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1769086644606\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira para colorir 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-01-22\/thumb_1769086644606.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1769086644606\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1770221590820\" data-ugc-likes=\"1\" data-ugc-title=\"io\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-02-04\/thumb_1770221590820.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1770221590820\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira para colorir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2026-02-04\/thumb_1770221590820.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1770221590820\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1771937537162\" data-ugc-likes=\"0\" data-ugc-title=\"Felix\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-24\/thumb_1771937537162.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1771937537162\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira para colorir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-02-24\/thumb_1771937537162.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1771937537162\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fexcavator.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<section class=\"shortcode-fullrow content-block\" data-insert=\"after-8\">\n  <div class=\"content-block__inner\">\n<h2>Do Papel ao Canteiro de Obras: Dicas para Colorir sua Escavadeira Caprichada<\/h2>\n\n<p>Colorir uma escavadeira \u00e9 como montar uma pequena cena de constru\u00e7\u00e3o: cada parte tem um formato e uma fun\u00e7\u00e3o. Para o desenho ficar bem bonito, vale observar com calma o <strong>bra\u00e7o articulado<\/strong>, a <strong>cabine<\/strong> e as <strong>esteiras<\/strong> (ou rodas), porque s\u00e3o as \u00e1reas que mais chamam aten\u00e7\u00e3o.<\/p>\n\n<blockquote class=\"info-box\">\n  <p><strong>Ideia r\u00e1pida:<\/strong> comece pelas \u00e1reas maiores (corpo da escavadeira), depois passe para as m\u00e9dias (cabine e bra\u00e7o) e finalize com as pequenas (parafusos, grades e luzes). Assim fica mais f\u00e1cil manter o desenho limpo e organizado.<\/p>\n<\/blockquote>\n\n<h3>No que prestar aten\u00e7\u00e3o ao colorir uma escavadeira<\/h3>\n<ul class=\"tip-list\">\n  <li><strong>Partes separadas:<\/strong> o corpo, o bra\u00e7o e a ca\u00e7amba costumam ter divis\u00f5es claras. Trocar levemente o tom entre essas pe\u00e7as ajuda a enxergar cada parte.<\/li>\n  <li><strong>Cabine com vidro:<\/strong> os vidros ficam melhores com azul ou cinza bem clarinho, deixando um pedacinho sem pintar para parecer brilho.<\/li>\n  <li><strong>Esteiras (ou pneus):<\/strong> geralmente s\u00e3o escuras. Pintar com cinza grafite e refor\u00e7ar as \u201cmarquinhas\u201d das ranhuras d\u00e1 um efeito de textura.<\/li>\n  <li><strong>Ca\u00e7amba:<\/strong> a ponta pode parecer um pouco mais escura, porque \u00e9 a parte que mais encosta no ch\u00e3o.<\/li>\n  <li><strong>Sombras simples:<\/strong> um tom um pouco mais escuro embaixo do bra\u00e7o, embaixo do corpo e perto das esteiras cria sensa\u00e7\u00e3o de peso, como uma m\u00e1quina de verdade.<\/li>\n  <li><strong>Detalhes pequenos:<\/strong> grades, degraus, corrim\u00e3os e luzes ficam mais f\u00e1ceis de pintar com l\u00e1pis bem apontado.<\/li>\n<\/ul>\n\n<h3>Cores realistas que combinam com escavadeira<\/h3>\n<p>As escavadeiras costumam ter uma cor principal forte, partes met\u00e1licas e \u00e1reas escuras (esteiras\/pneus). A tabela abaixo re\u00fane op\u00e7\u00f5es realistas para montar um visual bem \u201cde obra\u201d.<\/p>\n\n<figure class=\"wp-block-table\"><div class=\"table-wrapper\"><table class=\"info-table\">\n  <thead>\n    <tr>\n      <th>Parte da escavadeira<\/th>\n      <th>Cor sugerida<\/th>\n      <th>Exemplo<\/th>\n    <\/tr>\n  <\/thead>\n  <tbody>\n    <tr>\n      <td>Corpo principal<\/td>\n      <td>Amarelo constru\u00e7\u00e3o<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#F9C74F;\"><\/span> #F9C74F<\/td>\n    <\/tr>\n    <tr>\n      <td>Corpo principal (varia\u00e7\u00e3o comum)<\/td>\n      <td>Laranja seguran\u00e7a<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#F9844A;\"><\/span> #F9844A<\/td>\n    <\/tr>\n    <tr>\n      <td>Faixas e detalhes<\/td>\n      <td>Preto<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#111111;\"><\/span> #111111<\/td>\n    <\/tr>\n    <tr>\n      <td>Bra\u00e7o e articula\u00e7\u00f5es (sombras)<\/td>\n      <td>Amarelo mais escuro<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#DFAF2C;\"><\/span> #DFAF2C<\/td>\n    <\/tr>\n    <tr>\n      <td>Ca\u00e7amba (metal)<\/td>\n      <td>Cinza a\u00e7o<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#8D99AE;\"><\/span> #8D99AE<\/td>\n    <\/tr>\n    <tr>\n      <td>Parafusos, pinos e grades<\/td>\n      <td>Cinza escuro<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#4B5563;\"><\/span> #4B5563<\/td>\n    <\/tr>\n    <tr>\n      <td>Esteiras<\/td>\n      <td>Grafite<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#2F2F2F;\"><\/span> #2F2F2F<\/td>\n    <\/tr>\n    <tr>\n      <td>Vidros da cabine<\/td>\n      <td>Azul claro acinzentado<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#BFD7EA;\"><\/span> #BFD7EA<\/td>\n    <\/tr>\n    <tr>\n      <td>Interior\/assento (se aparecer)<\/td>\n      <td>Cinza m\u00e9dio<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#6B7280;\"><\/span> #6B7280<\/td>\n    <\/tr>\n    <tr>\n      <td>Luzes<\/td>\n      <td>Amarelo bem claro<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#FFF3B0;\"><\/span> #FFF3B0<\/td>\n    <\/tr>\n    <tr>\n      <td>Sombra no ch\u00e3o (embaixo da m\u00e1quina)<\/td>\n      <td>Cinza claro<\/td>\n      <td><span class=\"color-swatch\" style=\"background-color:#D1D5DB;\"><\/span> #D1D5DB<\/td>\n    <\/tr>\n  <\/tbody>\n<\/table><\/div><\/figure>\n\n<h3>Acabamento para um resultado bem \u201creal\u201d<\/h3>\n<ul class=\"tip-list\">\n  <li>Pinte o corpo com a cor principal e depois passe um tom um pouco mais escuro perto das bordas e embaixo das pe\u00e7as para criar profundidade.<\/li>\n  <li>Nos metais (ca\u00e7amba e pinos), use cinza e deixe uma linha fininha mais clara para parecer reflexo.<\/li>\n  <li>Nas esteiras, reforce as partes internas com grafite e deixe as bordas um pouco mais claras para destacar o formato.<\/li>\n<\/ul>\n  <\/div>\n<\/section>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbig-loader.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/big-loader.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/big-loader.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/big-loader.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/big-loader.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/big-loader.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/big-loader.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/big-loader.png\" alt=\"Imagem de grande carregadeira para colorir e imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Grande carregadeira para colorir e imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbig-loader.png\" style=\"text-decoration-line: none;\">Grande carregadeira para colorir e imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbig-loader.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/big-loader.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763673266834\" data-ugc-likes=\"3\" data-ugc-title=\"cat loader\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-20\/thumb_1763673266834.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763673266834\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir 3 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-20\/thumb_1763673266834.jpg\" alt=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763673266834\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">3 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763672951876\" data-ugc-likes=\"2\" data-ugc-title=\"loader\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-20\/thumb_1763672951876.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763672951876\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-20\/thumb_1763672951876.jpg\" alt=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763672951876\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1763215078643\" data-ugc-likes=\"1\" data-ugc-title=\"jonny\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-11-15\/thumb_1763215078643.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1763215078643\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-11-15\/thumb_1763215078643.jpg\" alt=\"Vers\u00e3o colorida: Grande carregadeira para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1763215078643\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fbig-loader.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-loader.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/heavy-loader.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/heavy-loader.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/heavy-loader.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/heavy-loader.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-loader.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/heavy-loader.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-loader.png\" alt=\"Pintura de p\u00e1 carregadeira pesada para colorir e imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Desenho de p\u00e1 carregadeira pesada para colorir e imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-loader.png\" style=\"text-decoration-line: none;\">Desenho de p\u00e1 carregadeira pesada para colorir e imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-loader.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-loader.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1761500185327\" data-ugc-likes=\"2\" data-ugc-title=\"Radlader\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-26\/thumb_1761500185327.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1761500185327\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-26\/thumb_1761500185327.jpg\" alt=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1761500185327\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1752178130699\" data-ugc-likes=\"2\" data-ugc-title=\"maxi\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-07-10\/thumb_1752178130699_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1752178130699\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir 2 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-07-10\/thumb_1752178130699_v1.jpg\" alt=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1752178130699\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">2 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1765218460435\" data-ugc-likes=\"0\" data-ugc-title=\"Radlader Mats\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-12-08\/thumb_1765218460435.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1765218460435\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-12-08\/thumb_1765218460435.jpg\" alt=\"Vers\u00e3o colorida: Desenho de p\u00e1 carregadeira pesada para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1765218460435\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fheavy-loader.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbackhoe.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/backhoe.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/backhoe.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/backhoe.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/backhoe.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/backhoe.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/backhoe.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/backhoe.png\" alt=\"Imagem de retroescavadeira para imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Retroescavadeira para imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbackhoe.png\" style=\"text-decoration-line: none;\">Retroescavadeira para imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbackhoe.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/backhoe.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1739741241413\" data-ugc-likes=\"5\" data-ugc-title=\"tractor fuerte\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-02-16\/thumb_1739741241413_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1739741241413\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Retroescavadeira para imprimir 5 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-02-16\/thumb_1739741241413_v1.jpg\" alt=\"Vers\u00e3o colorida: Retroescavadeira para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1739741241413\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">5 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1759862085165\" data-ugc-likes=\"1\" data-ugc-title=\"jonny\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-07\/thumb_1759862085165.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1759862085165\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Retroescavadeira para imprimir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-07\/thumb_1759862085165.jpg\" alt=\"Vers\u00e3o colorida: Retroescavadeira para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1759862085165\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1765200725068\" data-ugc-likes=\"0\" data-ugc-title=\"asdf\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-12-08\/thumb_1765200725068.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1765200725068\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Retroescavadeira para imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-12-08\/thumb_1765200725068.jpg\" alt=\"Vers\u00e3o colorida: Retroescavadeira para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1765200725068\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fbackhoe.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-bulldozer.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/heavy-bulldozer.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/heavy-bulldozer.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/heavy-bulldozer.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/heavy-bulldozer.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-bulldozer.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/heavy-bulldozer.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-bulldozer.png\" alt=\"Pintura de bulldozer pesado\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Desenho de bulldozer pesado\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-bulldozer.png\" style=\"text-decoration-line: none;\">Desenho de bulldozer pesado<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fheavy-bulldozer.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/heavy-bulldozer.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1754236691099\" data-ugc-likes=\"1\" data-ugc-title=\"loader\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-03\/thumb_1754236691099_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1754236691099\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de bulldozer pesado 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-03\/thumb_1754236691099_v1.jpg\" alt=\"Vers\u00e3o colorida: Desenho de bulldozer pesado\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1754236691099\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1767972446139\" data-ugc-likes=\"0\" data-ugc-title=\"rosa\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-09\/thumb_1767972446139.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1767972446139\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de bulldozer pesado 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-09\/thumb_1767972446139.jpg\" alt=\"Vers\u00e3o colorida: Desenho de bulldozer pesado\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1767972446139\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1741992387309\" data-ugc-likes=\"0\" data-ugc-title=\"Soldier of heaven\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-03-14\/thumb_1741992387309_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1741992387309\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de bulldozer pesado 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-03-14\/thumb_1741992387309_v1.jpg\" alt=\"Vers\u00e3o colorida: Desenho de bulldozer pesado\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1741992387309\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fheavy-bulldozer.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<section class=\"shortcode-fullrow content-block\" data-insert=\"after-12\">\n  <div class=\"content-block__inner\">\n<h2>Tesoura, Cola e Terra Imagin\u00e1ria: Artesanato com Escavadeira!<\/h2>\n\n<div class=\"craft-card\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/HowTo\">\n  <span class=\"craft-number\">1<\/span>\n  <div class=\"craft-content\">\n    <h3 class=\"craft-title\" itemprop=\"name\">Escavadeira 3D que Fica em P\u00e9<\/h3>\n    <p class=\"craft-supplies\" itemprop=\"supply\">\u2702\ufe0f Voc\u00ea vai precisar de: p\u00e1gina colorida de escavadeira, cartolina, tesoura sem ponta, cola, canetinhas ou l\u00e1pis de cor<\/p>\n    <ol class=\"craft-steps\">\n      <li itemprop=\"step\">Cole a escavadeira colorida em uma cartolina.<\/li>\n      <li itemprop=\"step\">Recorte o contorno com cuidado (com ajuda de um adulto).<\/li>\n      <li itemprop=\"step\">Corte uma tirinha de cartolina, dobre em \u201cV\u201d e cole atr\u00e1s para virar um pezinho.<\/li>\n    <\/ol>\n    <p class=\"craft-skill\">\ud83d\udca1 Desenvolve: coordena\u00e7\u00e3o motora fina, no\u00e7\u00e3o espacial, capricho ao recortar<\/p>\n  <\/div>\n<\/div>\n\n<div class=\"craft-card\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/HowTo\">\n  <span class=\"craft-number\">2<\/span>\n  <div class=\"craft-content\">\n    <h3 class=\"craft-title\" itemprop=\"name\">Pista de Constru\u00e7\u00e3o com Carimbos<\/h3>\n    <p class=\"craft-supplies\" itemprop=\"supply\">\u2702\ufe0f Voc\u00ea vai precisar de: papel grande (ou folhas coladas), tinta guache, um carrinho de brinquedo (ou rolinho), cotonetes, cola, pedacinhos de papel marrom<\/p>\n    <ol class=\"craft-steps\">\n      <li itemprop=\"step\">Pinte uma estrada e um \u201ccanteiro de obras\u201d no papel.<\/li>\n      <li itemprop=\"step\">Passe tinta nas rodinhas do carrinho e fa\u00e7a trilhas como carimbos.<\/li>\n      <li itemprop=\"step\">Cole pedacinhos de papel marrom como \u201cmontinhos de terra\u201d e finalize com detalhes de cotonete.<\/li>\n    <\/ol>\n    <p class=\"craft-skill\">\ud83d\udca1 Desenvolve: criatividade, coordena\u00e7\u00e3o motora, planejamento de espa\u00e7o no papel<\/p>\n  <\/div>\n<\/div>\n\n<div class=\"craft-card\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/HowTo\">\n  <span class=\"craft-number\">3<\/span>\n  <div class=\"craft-content\">\n    <h3 class=\"craft-title\" itemprop=\"name\">Mural da Turma: Cidade em Obras<\/h3>\n    <p class=\"craft-supplies\" itemprop=\"supply\">\u2702\ufe0f Voc\u00ea vai precisar de: v\u00e1rias p\u00e1ginas coloridas (escavadeiras e outros ve\u00edculos), papel kraft ou cartolina grande, cola, tesoura, l\u00e1pis de cor, algod\u00e3o<\/p>\n    <ol class=\"craft-steps\">\n      <li itemprop=\"step\">Cole um papel grande na parede ou em uma mesa para virar o mural.<\/li>\n      <li itemprop=\"step\">Cada crian\u00e7a recorta e cola sua escavadeira em um lugar do \u201ccanteiro\u201d.<\/li>\n      <li itemprop=\"step\">Desenhe ruas e pr\u00e9dios juntos e cole algod\u00e3o como \u201cnuvens de poeira\u201d bem clarinhas.<\/li>\n    <\/ol>\n    <p class=\"craft-skill\">\ud83d\udca1 Desenvolve: trabalho em equipe, comunica\u00e7\u00e3o, criatividade coletiva<\/p>\n  <\/div>\n<\/div>\n  <\/div>\n<\/section>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbulldozer.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/bulldozer.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/bulldozer.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/bulldozer.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/bulldozer.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/bulldozer.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/bulldozer.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/bulldozer.png\" alt=\"Imagem de bulldozer para imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Bulldozer para imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbulldozer.png\" style=\"text-decoration-line: none;\">Bulldozer para imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fbulldozer.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/bulldozer.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1760967525464\" data-ugc-likes=\"1\" data-ugc-title=\"Franz 1\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-20\/thumb_1760967525464.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1760967525464\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Bulldozer para imprimir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2025-10-20\/thumb_1760967525464.jpg\" alt=\"Vers\u00e3o colorida: Bulldozer para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1760967525464\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1754580117906\" data-ugc-likes=\"0\" data-ugc-title=\"digger\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-07\/thumb_1754580117906_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1754580117906\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Bulldozer para imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-07\/thumb_1754580117906_v1.jpg\" alt=\"Vers\u00e3o colorida: Bulldozer para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1754580117906\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1748734008813\" data-ugc-likes=\"0\" data-ugc-title=\"dante\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-05-31\/thumb_1748734008813_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1748734008813\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Bulldozer para imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-05-31\/thumb_1748734008813_v1.jpg\" alt=\"Vers\u00e3o colorida: Bulldozer para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1748734008813\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/digger.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/digger.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/digger.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/digger.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/digger.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger.png\" alt=\"Pintura de escavadeira\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Desenho de escavadeira\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger.png\" style=\"text-decoration-line: none;\">Desenho de escavadeira<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1759151964846\" data-ugc-likes=\"3\" data-ugc-title=\"Nisses Regnb\u00e5gsgr\u00e4vmaskin\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-09-29\/thumb_1759151964846.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1759151964846\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira 3 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-09-29\/thumb_1759151964846.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1759151964846\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">3 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1769537011479\" data-ugc-likes=\"1\" data-ugc-title=\"bn xmcxbvxc cmxvnx\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-27\/thumb_1769537011479.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1769537011479\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-27\/thumb_1769537011479.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1769537011479\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1769537026726\" data-ugc-likes=\"0\" data-ugc-title=\"krjg bgfkj cg,gbfjmrgkvdtrjngtjfg,mbfkgnhmgl skd112\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-27\/thumb_1769537026726.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1769537026726\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-27\/thumb_1769537026726.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1769537026726\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fdigger.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-on-construction-site.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/digger-on-construction-site.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/digger-on-construction-site.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/digger-on-construction-site.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/digger-on-construction-site.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-on-construction-site.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/digger-on-construction-site.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-on-construction-site.png\" alt=\"Imagem de escavadeira em canteiro de obras para imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Escavadeira em canteiro de obras para imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-on-construction-site.png\" style=\"text-decoration-line: none;\">Escavadeira em canteiro de obras para imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-on-construction-site.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-on-construction-site.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1737362259000\" data-ugc-likes=\"1\" data-ugc-title=\"\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-01-20\/thumb_1737362259000.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1737362259000\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-01-20\/thumb_1737362259000.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1737362259000\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1755776399586\" data-ugc-likes=\"0\" data-ugc-title=\"LEAN\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-21\/thumb_1755776399586_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1755776399586\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-08-21\/thumb_1755776399586_v1.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1755776399586\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1737362259000\" data-ugc-likes=\"0\" data-ugc-title=\"\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-01-20\/thumb_1737362259000_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1737362259000\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-01-20\/thumb_1737362259000_v1.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira em canteiro de obras para imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1737362259000\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Ffunny-digger-with-face.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/funny-digger-with-face.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/funny-digger-with-face.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/funny-digger-with-face.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/funny-digger-with-face.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/funny-digger-with-face.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/funny-digger-with-face.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/funny-digger-with-face.png\" alt=\"Pintura de escavadeira engra\u00e7ada com rosto\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Desenho de escavadeira engra\u00e7ada com rosto\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Ffunny-digger-with-face.png\" style=\"text-decoration-line: none;\">Desenho de escavadeira engra\u00e7ada com rosto<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Ffunny-digger-with-face.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/funny-digger-with-face.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1752948660068\" data-ugc-likes=\"1\" data-ugc-title=\"JULINA 61\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-07-19\/thumb_1752948660068_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1752948660068\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira engra\u00e7ada com rosto 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-07-19\/thumb_1752948660068_v1.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira engra\u00e7ada com rosto\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1752948660068\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1764514419317\" data-ugc-likes=\"0\" data-ugc-title=\"gravko\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-30\/thumb_1764514419317.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1764514419317\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira engra\u00e7ada com rosto 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-11-30\/thumb_1764514419317.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira engra\u00e7ada com rosto\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1764514419317\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n\n<section class=\"shortcode-fullrow content-block\" data-insert=\"after-16\">\n  <div class=\"content-block__inner\">\n<h2>Voc\u00ea Sabia? 5 Curiosidades de Escavadeira Que Parecem Magia!<\/h2>\n\n<div class=\"fact-card\">\n  <span class=\"fact-number\">1<\/span>\n  <div class=\"fact-content\">\n    <h3 class=\"fact-title\">O \u201cbra\u00e7o\u201d tem nome de verdade!<\/h3>\n    <p>A escavadeira tem um conjunto que parece um bra\u00e7o: a parte que vai e volta ajuda a alcan\u00e7ar longe, e a \u201cconcha\u201d (a p\u00e1) \u00e9 quem pega a terra, a areia ou a brita. \u00c9 como um bra\u00e7o gigante trabalhando com cuidado! <a href=\"https:\/\/www.infopedia.pt\/dicionarios\/lingua-portuguesa\/borboleta\" target=\"_blank\" rel=\"noreferrer noopener\">Infop\u00e9dia<\/a><\/p>\n  <\/div>\n<\/div>\n\n<div class=\"fact-card\">\n  <span class=\"fact-number\">2<\/span>\n  <div class=\"fact-content\">\n    <h3 class=\"fact-title\">Ela gira quase como um pi\u00e3o!<\/h3>\n    <p>Muitas escavadeiras conseguem girar a parte de cima em volta, sem precisar mexer a parte de baixo. Assim, elas podem pegar material de um lado e colocar do outro com rapidez, como se estivessem \u201cdan\u00e7ando\u201d no canteiro de obras. <a href=\"https:\/\/www.dinamac.com.br\/agricultura\/escavadeiras\/escavadeira-kawashima-ge36153-rebocavel\" target=\"_blank\" rel=\"noreferrer noopener\">dinamac.com.br<\/a><\/p>\n  <\/div>\n<\/div>\n\n<div class=\"fact-card\">\n  <span class=\"fact-number\">3<\/span>\n  <div class=\"fact-content\">\n    <h3 class=\"fact-title\">Esteiras ou rodas? Depende do ch\u00e3o!<\/h3>\n    <p>Algumas escavadeiras t\u00eam <strong>esteiras<\/strong>, que parecem \u201cp\u00e9s de lagarta\u201d e ajudam a n\u00e3o afundar em lugares com terra fofa. Outras t\u00eam <strong>rodas<\/strong>, que s\u00e3o boas para andar mais facilmente em ruas e pisos duros. <a href=\"https:\/\/pt.wikipedia.org\/wiki\/retroescavadeira\" target=\"_blank\" rel=\"noreferrer noopener\">Wikip\u00e9dia<\/a><\/p>\n  <\/div>\n<\/div>\n\n<div class=\"fact-card\">\n  <span class=\"fact-number\">4<\/span>\n  <div class=\"fact-content\">\n    <h3 class=\"fact-title\">Ela troca de \u201cm\u00e3os\u201d rapidinho<\/h3>\n    <p>A concha pode ser trocada por outras pe\u00e7as: algumas servem para abrir valas, outras para quebrar concreto e outras para agarrar objetos. \u00c9 como se a escavadeira colocasse ferramentas diferentes para cada miss\u00e3o! <a href=\"https:\/\/pt.wikipedia.org\/wiki\/retroescavadeira\" target=\"_blank\" rel=\"noreferrer noopener\">Wikip\u00e9dia<\/a><\/p>\n  <\/div>\n<\/div>\n\n<div class=\"fact-card\">\n  <span class=\"fact-number\">5<\/span>\n  <div class=\"fact-content\">\n    <h3 class=\"fact-title\">Ajuda a construir cidades no Brasil<\/h3>\n    <p>Escavadeiras s\u00e3o muito usadas em obras de estradas, pontes e saneamento (como canos de \u00e1gua e esgoto) em v\u00e1rias regi\u00f5es do Brasil, ajudando a preparar o terreno para a cidade funcionar melhor. <a href=\"https:\/\/concla.ibge.gov.br\/images\/concla\/downloads\/cnae-subclasses-2-2-notas-explicativas.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">IBGE<\/a><\/p>\n  <\/div>\n<\/div>\n  <\/div>\n<\/section>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fsmall-digger.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/small-digger.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/small-digger.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/small-digger.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/small-digger.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/small-digger.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/small-digger.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/small-digger.png\" alt=\"Imagem de escavadeira pequena para colorir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Escavadeira pequena para colorir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fsmall-digger.png\" style=\"text-decoration-line: none;\">Escavadeira pequena para colorir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fsmall-digger.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/small-digger.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1772366794307\" data-ugc-likes=\"1\" data-ugc-title=\"zhik\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-01\/thumb_1772366794307.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1772366794307\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira pequena para colorir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-03-01\/thumb_1772366794307.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira pequena para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1772366794307\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1769791526604\" data-ugc-likes=\"1\" data-ugc-title=\"Baggy\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-30\/thumb_1769791526604.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1769791526604\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira pequena para colorir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-30\/thumb_1769791526604.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira pequena para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1769791526604\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd48\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f948.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1769090268505\" data-ugc-likes=\"0\" data-ugc-title=\"\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-22\/thumb_1769090268505.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1769090268505\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Escavadeira pequena para colorir 0 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/happycolorz\/2026-01-22\/thumb_1769090268505.jpg\" alt=\"Vers\u00e3o colorida: Escavadeira pequena para colorir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1769090268505\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd49\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f949.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">0 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep\">\n    <p class=\"ugc-more-link\"><a href=\"https:\/\/www.colomio.com\/pt-pt\/colored?svgUrl=https%3A%2F%2Fmedia.colomio.com%2Ft%2F500x500%2Fvehicles%2Fexcavator%2Fsmall-digger.svg&#038;limit=100&#038;offset=0&#038;sort=likes\">Ver tudo<\/a><\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-with-driver.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/digger-with-driver.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/digger-with-driver.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/digger-with-driver.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/digger-with-driver.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-with-driver.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/digger-with-driver.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-with-driver.png\" alt=\"Imagem de escavadeira com operador para imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Escavadeira com operador para imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-with-driver.png\" style=\"text-decoration-line: none;\">Escavadeira com operador para imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fdigger-with-driver.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-with-driver.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) - Still blank -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" data-ugc-empty=\"true\" aria-label=\"Modelos coloridos pela comunidade\" style=\"height:100%;\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-0 uppercase tracking-widest\" style=\"margin-bottom: 0;\">\n      <a href=\"#\" class=\"malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/digger-with-driver.png\">\n        <big>Ainda em branco. Pinte agora  <\/big><img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji\" alt=\"\ud83c\udfa8\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f3a8.svg\">\n      <\/a>\n    <\/p>\n  <\/div>\n<\/figure>\n\n<figure class=\"bg-white shadow-md rounded-lg overflow-hidden\">\n  <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fcute-digger.png\">\n    <picture>\n      <source srcset=\"https:\/\/media.colomio.com\/t\/webp\/300x300\/vehicles\/excavator\/cute-digger.webp 300w,\n                        https:\/\/media.colomio.com\/t\/webp\/500x500\/vehicles\/excavator\/cute-digger.webp 500w,\n                        https:\/\/media.colomio.com\/t\/webp\/800x800\/vehicles\/excavator\/cute-digger.webp 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/webp\">\n      <source srcset=\"https:\/\/media.colomio.com\/t\/300x300\/vehicles\/excavator\/cute-digger.png 300w,\n                        https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/cute-digger.png 500w,\n                        https:\/\/media.colomio.com\/t\/800x800\/vehicles\/excavator\/cute-digger.png 800w\" sizes=\"(max-width: 600px) 300px,\n                     (max-width: 900px) 500px,\n                     800px\" type=\"image\/png\">\n      <img decoding=\"async\" src=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/cute-digger.png\" alt=\"Pintura de escavadeira fofa para colorir e imprimir\" class=\"w-full h-64 md:h-48 object-contain\" title=\"Desenho de escavadeira fofa para colorir e imprimir\" loading=\"lazy\" itemprop=\"contentUrl\">\n    <\/picture>\n  <\/a>\n  <figcaption class=\"p-4 text-gray-600 text-center\">\n    <a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fcute-digger.png\" style=\"text-decoration-line: none;\">Desenho de escavadeira fofa para colorir e imprimir<\/a>\n  <\/figcaption>\n  <center><a href=\"https:\/\/www.colomio.com\/pt-pt\/personalized-coloring-pt-pt?bildId=null&#038;bildUrl=vehicles%2Fexcavator%2Fcute-digger.png\" class=\"button ap\" style=\"background: #fe6a00;color: #ffffff;display:inline-block;margin-bottom: 10px;\">Desenho para colorir gr\u00e1tis<\/a><\/center>\n  <center><a href=\"#\" class=\"button malvorlage-link\" data-image=\"https:\/\/media.colomio.com\/t\/500x500\/vehicles\/excavator\/cute-digger.png\" style=\"color: #ffffff;display:inline-block;margin-bottom: 10px;\">Colorir online<\/a><\/center>\n  <!-- COMMUNITY GALERIE (UGC) -->\n  <div class=\"p-3\" data-ugc-gallery=\"true\" aria-label=\"Modelos coloridos pela comunidade\">\n    <p class=\"text-[10px] font-bold text-gray-400 mb-2 uppercase tracking-widest\">\n      Modelos coloridos pela comunidade\n    <\/p>\n    <div class=\"cs-thumbs flex flex-wrap gap-2\">\n\n      <div class=\"ugc-thumb-item\">\n        <button type=\"button\" class=\"cs-thumb-btn group relative\" data-ugc=\"true\" data-ugc-id=\"1757436434641\" data-ugc-likes=\"1\" data-ugc-title=\"Radlader\" data-ugc-thumb=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-09-09\/thumb_1757436434641_v1.jpg\" data-ugc-href=\"\/pt-pt\/colored?id=1757436434641\" onclick=\"event.stopPropagation();location=this.dataset.ugcHref\" aria-label=\"Vers\u00e3o colorida: Desenho de escavadeira fofa para colorir e imprimir 1 Likes.\">\n        <div class=\"cs-thumb-wrapper\">\n          <img class=\"cs-thumb w-12 h-12 rounded shadow-sm border-2 border-white group-hover:border-green-400 transition object-cover\" src=\"https:\/\/image-header-a3zqg.ondigitalocean.app\/new\/images\/colomio\/2025-09-09\/thumb_1757436434641_v1.jpg\" alt=\"Vers\u00e3o colorida: Desenho de escavadeira fofa para colorir e imprimir\" loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" data-ts=\"1757436434641\">\n        <\/div>\n        <\/button>\n        <div class=\"ugc-rank-wrapper is-hidden\">\n          <img decoding=\"async\" draggable=\"false\" role=\"img\" class=\"emoji ugc-medal-emoji\" alt=\"\ud83e\udd47\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f947.svg\">\n        <\/div>\n        <span class=\"ugc-like\" aria-hidden=\"true\" style=\"cursor:default\">1 <svg class=\"ugc-like-icon\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\" style=\"cursor:default\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M7 11v10H4a1 1 0 0 1-1-1v-8a1 1 0 0 1 1-1h3Zm2 10V11l5-8a2 2 0 0 1 3.6 1.2L16.5 11H20a2 2 0 0 1 1.9 2.6l-2 6A2 2 0 0 1 18 21H9Z\" stroke=\"currentColor\" stroke-width=\"1.8\" stroke-linejoin=\"round\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n      <\/div>\n\n    <\/div>\n    <hr class=\"ugc-more-sep is-hidden\" aria-hidden=\"true\">\n    <p class=\"ugc-more-link is-hidden\" aria-hidden=\"true\"><span>Ver tudo<\/span><\/p>\n  <\/div>\n<\/figure>\n<\/div><\/div>\n\n<!-- 0126-footertext-start -->\n<h2>Por que as Crian\u00e7as Adoram Estas P\u00e1ginas para Colorir da Escavadora<\/h2>\n<ul>\n  <li>Desenvolvem a coordena\u00e7\u00e3o motora fina e o reconhecimento de cores ao seguir linhas e detalhes da escavadora.<\/li>\n  <li>Permitem actividades educativas simples, como contar pe\u00e7as da m\u00e1quina ou identificar partes (bra\u00e7o, pala, lagartas), \u00fateis para professores e pais.<\/li>\n  <li>Todas as p\u00e1ginas para colorir nesta p\u00e1gina s\u00e3o gratuitas para descarregar e imprimir e podem ser usadas gratuitamente na escola e no jardim de inf\u00e2ncia (o uso em sala de aula \u00e9 permitido).<\/li>\n  <li>S\u00e3o uma alternativa sem ecr\u00e3 que ocupa as crian\u00e7as durante viagens, intervalos ou projetos de ensino, promovendo concentra\u00e7\u00e3o e criatividade.<\/li>\n<\/ul>\n\n<h2>Ideias Criativas e Atividades<\/h2>\n<ol>\n  <li>Transforme a p\u00e1gina da escavadora numa marioneta recortando a figura, colando-a num pau de gelado e adicionando rodas de cart\u00e3o para um brinquedo simples.<\/li>\n  <li>Use v\u00e1rias p\u00e1ginas para criar um livro ilustrado onde cada crian\u00e7a desenha uma cena diferente em que a escavadora ajuda numa obra ou num resgate, desenvolvendo narrativa e sequ\u00eancia.<\/li>\n  <li>Fa\u00e7a um jogo de correspond\u00eancia: imprima duas c\u00f3pias, pinte as escavadoras com cores diferentes e jogue pares ou mem\u00f3ria para treinar a mem\u00f3ria visual.<\/li>\n  <li>Proponha uma oficina de texturas onde as crian\u00e7as colam areia, tecido ou papel de embrulho nas zonas da escavadora para explorar tacto e colagem criativa.<\/li>\n  <li>Utilize a p\u00e1gina para ensinar medidas simples: pe\u00e7a \u00e0s crian\u00e7as que desenhem sombras, calculem quantas palas cabem numa linha ou comparem tamanhos de escavadoras.<\/li>\n  <li>Organize uma actividade de matem\u00e1tica contando pe\u00e7as da escavadora e convertendo em somas ou tabelas para introduzir conceitos de adi\u00e7\u00e3o e classifica\u00e7\u00e3o.<\/li>\n  <li>Crie um mural de sala de aula com v\u00e1rias escavadoras pintadas pelas crian\u00e7as para trabalhar trabalho em equipa e apresenta\u00e7\u00e3o de projetos.<\/li>\n  <li>Integre a escavadora em dramatiza\u00e7\u00f5es: as crian\u00e7as criam um pequeno gui\u00e3o onde a m\u00e1quina resolve um problema, estimulando express\u00e3o oral e criatividade.<\/li>\n<\/ol>\n\n<h2>Perguntas Frequentes<\/h2>\n<h3>Estas p\u00e1ginas para colorir s\u00e3o realmente gratuitas?<\/h3>\n<p>Sim \u2014 todas as p\u00e1ginas para colorir desta p\u00e1gina s\u00e3o gratuitas para descarregar e imprimir. Pode us\u00e1-las sem custos em casa, na escola ou no jardim de inf\u00e2ncia.<\/p>\n\n<h3>Em que formatos v\u00eam os ficheiros e como os posso imprimir?<\/h3>\n<p>As p\u00e1ginas est\u00e3o dispon\u00edveis em formatos comuns como PDF e JPG, preparados para impress\u00e3o direta. Para melhores resultados, abra o PDF ou a imagem em visualizador e escolha \u201ctamanho real\u201d ou \u201cajustar \u00e0 p\u00e1gina\u201d antes de imprimir.<\/p>\n\n<h3>Para que idades s\u00e3o adequadas as p\u00e1ginas da escavadora?<\/h3>\n<p>As p\u00e1ginas s\u00e3o adequadas para uma ampla faixa et\u00e1ria, desde pr\u00e9-escolar at\u00e9 crian\u00e7as do ensino b\u00e1sico, dependendo do n\u00edvel de detalhe escolhido. Professores e pais podem adaptar a actividade simplificando ou acrescentando desafios conforme a idade.<\/p>\n\n<h3>Posso usar estas p\u00e1ginas em sala de aula ou no jardim de inf\u00e2ncia?<\/h3>\n<p>Sim, pode usar as p\u00e1ginas gratuitamente na escola e no jardim de inf\u00e2ncia; o uso em sala de aula \u00e9 permitido. S\u00e3o ideais para trabalhos em grupo, tarefas individuais e actividades tem\u00e1ticas.<\/p>\n\n<h3>Como consigo os melhores resultados ao colorir as escavadoras?<\/h3>\n<p>Use papel com gramagem ligeiramente superior (120\u2013160 g\/m\u00b2) para evitar que marcadores perfurem, e prefira l\u00e1pis de cera ou l\u00e1pis de cor para melhor controlo; os marcadores funcionam bem em papel mais grosso. Experimente t\u00e9cnicas simples como sombreado, mistura de cores e contornos a caneta preta para real\u00e7ar detalhes.<\/p>\n<!-- 0126-footertext-end -->\n\n<!-- \/wp:post-content --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform --><!-- \/wp:freeform -->","protected":false},"excerpt":{"rendered":"<p>As p\u00e1ginas para colorir de escavadoras s\u00e3o desenhos simples e divertidos que permitem \u00e0s crian\u00e7as pintar cenas com m\u00e1quinas de constru\u00e7\u00e3o, desde a escavadora cl\u00e1ssica at\u00e9 modelos mais modernos. Uma p\u00e1gina para colorir de escavadora oferece contornos claros e \u00e1reas amplas para crian\u00e7as mais novas, enquanto conjuntos de p\u00e1ginas para colorir podem incluir detalhes adicionais &#8230; <a title=\"P\u00e1gina para colorir com escavadeira: imprima gr\u00e1tis, escolha as cores e m\u00e3os \u00e0 obra!\" class=\"read-more\" href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\" aria-label=\"Leia mais sobre P\u00e1gina para colorir com escavadeira: imprima gr\u00e1tis, escolha as cores e m\u00e3os \u00e0 obra!\">Ler mais<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":3766,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_yoast_wpseo_title":"Desenhos de Escavadeiras para Imprimir e Colorir","_yoast_wpseo_metadesc":"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira & mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.","_yoast_wpseo_bctitle":"Escavadoras","_colomio_max_video_preview":"","_colomio_max_image_preview":"","_colomio_max_snippet":"","_custom_article_jsonld":"","_custom_howto_jsonld":"","_custom_schema_jsonld":"","category-page":true,"footnotes":""},"class_list":["post-3797","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desenhos de Escavadeiras para Imprimir e Colorir<\/title>\n<meta name=\"description\" content=\"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira &amp; mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenhos de Escavadeiras para Imprimir e Colorir\" \/>\n<meta property=\"og:description\" content=\"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira &amp; mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\" \/>\n<meta property=\"og:site_name\" content=\"www.colomio.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T15:01:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\",\"url\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\",\"name\":\"Desenhos de Escavadeiras para Imprimir e Colorir\",\"isPartOf\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\",\"datePublished\":\"2025-02-21T11:03:25+00:00\",\"dateModified\":\"2026-04-21T15:01:08+00:00\",\"description\":\"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira & mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage\",\"url\":\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\",\"contentUrl\":\"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.colomio.com\/pt-pt\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desenhos para Colorir\",\"item\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ve\u00edculos\",\"item\":\"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Escavadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt#website\",\"url\":\"https:\/\/www.colomio.com\/pt-pt\",\"name\":\"www.colomio.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colomio.com\/pt-pt?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt#organization\",\"name\":\"colomio\",\"url\":\"https:\/\/www.colomio.com\/pt-pt\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colomio.com\/wp-content\/uploads\/2025\/02\/cropped-colomio-logo.png?wsr\",\"contentUrl\":\"https:\/\/www.colomio.com\/wp-content\/uploads\/2025\/02\/cropped-colomio-logo.png?wsr\",\"width\":373,\"height\":98,\"caption\":\"www.colomio.com\"},\"image\":{\"@id\":\"https:\/\/www.colomio.com\/pt-pt#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/colomio.team\/\",\"https:\/\/de.pinterest.com\/happycolorz_colomio\/\",\"https:\/\/www.pinterest.com\/happycolorz_colomio\/\",\"https:\/\/www.muminthemadhouse.com\/custom-ai-colouring-pages-for-kids\/\",\"https:\/\/slummysinglemummy.com\/2026\/03\/05\/rainy-afternoons-just-got-a-lot-more-creative-discovering-colomio\/\",\"https:\/\/www.amazon.com\/Horses-Coloring-Book-pages-reprint\/dp\/1707878994\",\"https:\/\/www.prnewswire.com\/news-releases\/colomiocom-launches-a-free-customizable-coloring-book-for-home-printing-301162753.html\",\"https:\/\/www.linkedin.com\/in\/mathias-ziegler-b6068568\/\"],\"alternateName\":\"colomio.com\",\"foundingDate\":\"2019\",\"description\":\"Free printable coloring pages, step-by-step drawing tutorials, and creative crafts for kids \u2013 created by parents, tested by children.\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Zeppelinstr. 73\",\"addressLocality\":\"Munich\",\"postalCode\":\"81669\",\"addressRegion\":\"Bavaria\",\"addressCountry\":\"DE\"},\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"happycolorz GmbH\",\"url\":\"https:\/\/www.happycolorz.de\"},\"founder\":[{\"@type\":\"Person\",\"@id\":\"https:\/\/www.colomio.com\/pt-pt#mathias\/\",\"name\":\"Mathias Ziegler\",\"jobTitle\":\"Founder & Managing Director\",\"url\":\"https:\/\/www.colomio.com\/pt-pt\/authors\/colomio-team\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenhos de Escavadeiras para Imprimir e Colorir","description":"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira & mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira","og_locale":"pt_PT","og_type":"article","og_title":"Desenhos de Escavadeiras para Imprimir e Colorir","og_description":"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira & mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.","og_url":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira","og_site_name":"www.colomio.com","article_modified_time":"2026-04-21T15:01:08+00:00","og_image":[{"url":"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira","url":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira","name":"Desenhos de Escavadeiras para Imprimir e Colorir","isPartOf":{"@id":"https:\/\/www.colomio.com\/pt-pt#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage"},"image":{"@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage"},"thumbnailUrl":"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png","datePublished":"2025-02-21T11:03:25+00:00","dateModified":"2026-04-21T15:01:08+00:00","description":"Desenhos de escavadeiras para imprimir e colorir \u2705 Escavadeira \u2714 Escavadeira de esteira \u2714 Escavadeira de p\u00e1 \u2714 Bulldozer \u2714 Operador de escavadeira & mais desenhos para colorir gratuitos para imprimir \u270e descubra colomio.","breadcrumb":{"@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#primaryimage","url":"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png","contentUrl":"https:\/\/media.colomio.com\/t\/500x500\/new\/vehicles\/excavator\/excavator-coloring-page-bucket-tracks.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos\/escavadeira#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.colomio.com\/pt-pt"},{"@type":"ListItem","position":2,"name":"Desenhos para Colorir","item":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir"},{"@type":"ListItem","position":3,"name":"Ve\u00edculos","item":"https:\/\/www.colomio.com\/pt-pt\/desenhos-para-colorir\/veiculos"},{"@type":"ListItem","position":4,"name":"Escavadoras"}]},{"@type":"WebSite","@id":"https:\/\/www.colomio.com\/pt-pt#website","url":"https:\/\/www.colomio.com\/pt-pt","name":"www.colomio.com","description":"","publisher":{"@id":"https:\/\/www.colomio.com\/pt-pt#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colomio.com\/pt-pt?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.colomio.com\/pt-pt#organization","name":"colomio","url":"https:\/\/www.colomio.com\/pt-pt","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.colomio.com\/pt-pt#\/schema\/logo\/image\/","url":"https:\/\/www.colomio.com\/wp-content\/uploads\/2025\/02\/cropped-colomio-logo.png?wsr","contentUrl":"https:\/\/www.colomio.com\/wp-content\/uploads\/2025\/02\/cropped-colomio-logo.png?wsr","width":373,"height":98,"caption":"www.colomio.com"},"image":{"@id":"https:\/\/www.colomio.com\/pt-pt#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/colomio.team\/","https:\/\/de.pinterest.com\/happycolorz_colomio\/","https:\/\/www.pinterest.com\/happycolorz_colomio\/","https:\/\/www.muminthemadhouse.com\/custom-ai-colouring-pages-for-kids\/","https:\/\/slummysinglemummy.com\/2026\/03\/05\/rainy-afternoons-just-got-a-lot-more-creative-discovering-colomio\/","https:\/\/www.amazon.com\/Horses-Coloring-Book-pages-reprint\/dp\/1707878994","https:\/\/www.prnewswire.com\/news-releases\/colomiocom-launches-a-free-customizable-coloring-book-for-home-printing-301162753.html","https:\/\/www.linkedin.com\/in\/mathias-ziegler-b6068568\/"],"alternateName":"colomio.com","foundingDate":"2019","description":"Free printable coloring pages, step-by-step drawing tutorials, and creative crafts for kids \u2013 created by parents, tested by children.","address":{"@type":"PostalAddress","streetAddress":"Zeppelinstr. 73","addressLocality":"Munich","postalCode":"81669","addressRegion":"Bavaria","addressCountry":"DE"},"parentOrganization":{"@type":"Organization","name":"happycolorz GmbH","url":"https:\/\/www.happycolorz.de"},"founder":[{"@type":"Person","@id":"https:\/\/www.colomio.com\/pt-pt#mathias\/","name":"Mathias Ziegler","jobTitle":"Founder & Managing Director","url":"https:\/\/www.colomio.com\/pt-pt\/authors\/colomio-team"}]}]}},"_links":{"self":[{"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3797"}],"version-history":[{"count":166,"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3797\/revisions"}],"predecessor-version":[{"id":169806,"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3797\/revisions\/169806"}],"up":[{"embeddable":true,"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/pages\/3766"}],"wp:attachment":[{"href":"https:\/\/www.colomio.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}